{"id":133,"date":"2022-11-25T14:56:48","date_gmt":"2022-11-25T14:56:48","guid":{"rendered":"https:\/\/oldies.gold\/?page_id=133"},"modified":"2022-11-25T14:56:48","modified_gmt":"2022-11-25T14:56:48","slug":"schedule","status":"publish","type":"page","link":"https:\/\/oldies.gold\/index.php\/schedule\/","title":{"rendered":"Schedule"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-133","page","type-page","status-publish","hentry","post"],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/oldies.gold\/index.php\/wp-json\/wp\/v2\/pages\/133","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/oldies.gold\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/oldies.gold\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/oldies.gold\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/oldies.gold\/index.php\/wp-json\/wp\/v2\/comments?post=133"}],"version-history":[{"count":1,"href":"https:\/\/oldies.gold\/index.php\/wp-json\/wp\/v2\/pages\/133\/revisions"}],"predecessor-version":[{"id":135,"href":"https:\/\/oldies.gold\/index.php\/wp-json\/wp\/v2\/pages\/133\/revisions\/135"}],"wp:attachment":[{"href":"https:\/\/oldies.gold\/index.php\/wp-json\/wp\/v2\/media?parent=133"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}